{"id":8313,"date":"2023-07-29T20:54:12","date_gmt":"2023-07-29T11:54:37","guid":{"rendered":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/diagnosis-solutions\/basic-diagnosis-copy\/"},"modified":"2023-08-29T14:06:34","modified_gmt":"2023-08-29T05:06:34","slug":"falcon","status":"publish","type":"page","link":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/diagnosis-solutions\/falcon\/","title":{"rendered":"\u9023\u7d9a\u8a3a\u65ad"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#364FDC&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;page-header-solution&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;\u8a3a\u65ad\u30b5\u30fc\u30d3\u30b9:&#8221; font_container=&#8221;tag:div|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;hd-subheading&#8221;][vc_custom_heading text=&#8221;\u9023\u7d9a\u8a3a\u65ad&#8221; font_container=&#8221;tag:h1|text_align:left&#8221; el_class=&#8221;hd-subheading&#8221;][vc_custom_heading text=&#8221;Continuous Diagnosis&#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;hd-subheading&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8552&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8479&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<ul>\n<li>\u7279\u5225\u9ad8\u5727\u914d\u96fb\u76e4\u3001\u30b1\u30fc\u30d6\u30eb\u3001\u5909\u5727\u5668\u3001\u30e2\u30fc\u30bf\u30fc\u306a\u3069\u96fb\u6c17\u8a2d\u5099\u306e\u90e8\u5206\u653e\u96fb\u3092\u9023\u7d9a\u76e3\u8996\u3059\u308b\u305f\u3081\u306e\u88c5\u7f6e<\/li>\n<li><em>T-F\u30de\u30c3\u30d4\u30f3\u30b0\u6280\u8853<\/em>\u3067\u3001\u30ce\u30a4\u30ba\u3068\u653e\u96fb\u306e\u81ea\u52d5\u5f01\u5225\u3092\u884c\u3044\u30c7\u30fc\u30bf\u89e3\u6790\u51e6\u7406\u3092\u884c\u3046<\/li>\n<li>\u30bb\u30f3\u30b5\u306f\u3001HFCT\u3001TEV\u3001FMC\u7b49\u304c\u4f7f\u7528\u3067\u304d\u308b<\/li>\n<li>CableWise\u3067\u7570\u5e38\u304c\u691c\u51fa\u3055\u308c\u305f\u6642\u306b\u3001<em>\u4e00\u5b9a\u671f\u9593\u9023\u7d9a\u76e3\u8996<\/em>\u3092\u884c\u3046\u306e\u306b\u9069\u3057\u3066\u3044\u308b<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8485&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<ul>\n<li>\u30e2\u30b8\u30e5\u30fc\u30eb\u5f0f\u3067\u3001\u6a19\u6e96\u7684\u306a\u30e9\u30c3\u30af\u30de\u30a6\u30f3\u30c8\u306e\uff16U\u30e2\u30b8\u30e5\u30fc\u30eb\u306b\u6700\u592740\u30c1\u30e3\u30f3\u30cd\u30eb\u3092\u642d\u8f09\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u3001\u7279\u9ad8\u5909\u96fb\u6240\u306e\u914d\u96fb\u76e4\u3092\u6700\u592720\u53f0\u307e\u3067\u76e3\u8996\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u308b<\/li>\n<li><em>T-F\u30de\u30c3\u30d4\u30f3\u30b0\u6280\u8853<\/em>\u3067\u3001\u30ce\u30a4\u30ba\u3068\u653e\u96fb\u306e\u81ea\u52d5\u5f01\u5225\u3092\u884c\u3044\u30c7\u30fc\u30bf\u89e3\u6790\u51e6\u7406\u3092\u884c\u3046<\/li>\n<li>\u30bb\u30f3\u30b5\u306f\u90e8\u5206\u653e\u96fb\u4fe1\u53f7\u7528\u306bHFCT\u3001TEV FMC\u7b49\u304c\u4f7f\u7528\u3067\u304d\u308b<\/li>\n<li><em>\u4e2d\u5c0f\u898f\u6a21\u306e\u9ad8\u5ea6\u76e3\u8996\u5316<\/em>\u306b\u9069\u3057\u3066\u3044\u308b<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner]<div class=\"ult-spacer spacer-6a97b9cf08ea8\" data-id=\"6a97b9cf08ea8\" data-height=\"40\" data-height-mobile=\"40\" data-height-tab=\"40\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8040,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8313","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/pages\/8313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/comments?post=8313"}],"version-history":[{"count":14,"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/pages\/8313\/revisions"}],"predecessor-version":[{"id":8739,"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/pages\/8313\/revisions\/8739"}],"up":[{"embeddable":true,"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/pages\/8040"}],"wp:attachment":[{"href":"https:\/\/www.towaelex.co.jp\/diagnosis-solutions\/wp-json\/wp\/v2\/media?parent=8313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}